{"id":10000817,"date":"2026-07-15T09:08:19","date_gmt":"2026-07-15T16:08:19","guid":{"rendered":"https:\/\/www.reddevelopment.com\/pvphx\/?post_type=tribe_events&#038;p=4323"},"modified":"2026-07-15T09:08:19","modified_gmt":"2026-07-15T16:08:19","slug":"backdoor-chicken-mondays-velvet-taco","status":"publish","type":"tribe_events","link":"https:\/\/www.reddevelopment.com\/pvphx\/event\/backdoor-chicken-mondays-velvet-taco\/2026-08-03\/","title":{"rendered":"Backdoor Chicken Mondays | Velvet Taco"},"content":{"rendered":"<p>Every Monday at PV, Velvet Taco offers Backdoor Chicken for $20. This includes 1 whole rotisserie chicken, 1 queso, 1 guac, 1 corn pico, 6 tortillas, chips and hot sauces for just $20!<\/p>\n<p>This deal is to-go only and happens every Monday!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Every Monday at PV, Velvet Taco offers Backdoor Chicken for $20. This includes 1 whole rotisserie chicken, 1 queso, 1 guac, 1 corn pico, 6 tortillas, chips and hot sauces&#8230;<\/p>\n","protected":false},"author":60,"featured_media":4324,"template":"","meta":{"_acf_changed":false,"_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":""},"tags":[],"tribe_events_cat":[],"class_list":["post-10000817","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tribe-recurring-event","tribe-recurring-event-parent"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Backdoor Chicken Mondays | Velvet Taco - Things to do at PV<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.reddevelopment.com\/pvphx\/event\/backdoor-chicken-mondays-velvet-taco\/2026-08-03\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Backdoor Chicken Mondays | Velvet Taco - Things to do at PV\" \/>\n<meta property=\"og:description\" content=\"Every Monday at PV, Velvet Taco offers Backdoor Chicken for $20. This includes 1 whole rotisserie chicken, 1 queso, 1 guac, 1 corn pico, 6 tortillas, chips and hot sauces...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.reddevelopment.com\/pvphx\/event\/backdoor-chicken-mondays-velvet-taco\/2026-08-03\/\" \/>\n<meta property=\"og:site_name\" content=\"PV\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.reddevelopment.com\/pvphx\/wp-content\/uploads\/sites\/32\/2026\/07\/Screenshot-2026-07-15-110507-1024x880.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"880\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.reddevelopment.com\\\/pvphx\\\/event\\\/backdoor-chicken-mondays-velvet-taco\\\/2026-08-03\\\/\",\"url\":\"https:\\\/\\\/www.reddevelopment.com\\\/pvphx\\\/event\\\/backdoor-chicken-mondays-velvet-taco\\\/2026-08-03\\\/\",\"name\":\"Backdoor Chicken Mondays | Velvet Taco - Things to do at PV\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.reddevelopment.com\\\/pvphx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.reddevelopment.com\\\/pvphx\\\/event\\\/backdoor-chicken-mondays-velvet-taco\\\/2026-08-03\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.reddevelopment.com\\\/pvphx\\\/event\\\/backdoor-chicken-mondays-velvet-taco\\\/2026-08-03\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.reddevelopment.com\\\/pvphx\\\/wp-content\\\/uploads\\\/sites\\\/32\\\/2026\\\/07\\\/Screenshot-2026-07-15-110507.png\",\"datePublished\":\"2026-07-15T16:08:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.reddevelopment.com\\\/pvphx\\\/event\\\/backdoor-chicken-mondays-velvet-taco\\\/2026-08-03\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.reddevelopment.com\\\/pvphx\\\/event\\\/backdoor-chicken-mondays-velvet-taco\\\/2026-08-03\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.reddevelopment.com\\\/pvphx\\\/event\\\/backdoor-chicken-mondays-velvet-taco\\\/2026-08-03\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.reddevelopment.com\\\/pvphx\\\/wp-content\\\/uploads\\\/sites\\\/32\\\/2026\\\/07\\\/Screenshot-2026-07-15-110507.png\",\"contentUrl\":\"https:\\\/\\\/www.reddevelopment.com\\\/pvphx\\\/wp-content\\\/uploads\\\/sites\\\/32\\\/2026\\\/07\\\/Screenshot-2026-07-15-110507.png\",\"width\":1130,\"height\":971},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.reddevelopment.com\\\/pvphx\\\/event\\\/backdoor-chicken-mondays-velvet-taco\\\/2026-08-03\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.reddevelopment.com\\\/pvphx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Events\",\"item\":\"https:\\\/\\\/www.reddevelopment.com\\\/pvphx\\\/events\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Backdoor Chicken Mondays | Velvet Taco\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.reddevelopment.com\\\/pvphx\\\/#website\",\"url\":\"https:\\\/\\\/www.reddevelopment.com\\\/pvphx\\\/\",\"name\":\"PV\",\"description\":\"A RED Development Mixed Use Landmark Property\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.reddevelopment.com\\\/pvphx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Backdoor Chicken Mondays | Velvet Taco - Things to do at PV","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.reddevelopment.com\/pvphx\/event\/backdoor-chicken-mondays-velvet-taco\/2026-08-03\/","og_locale":"en_US","og_type":"article","og_title":"Backdoor Chicken Mondays | Velvet Taco - Things to do at PV","og_description":"Every Monday at PV, Velvet Taco offers Backdoor Chicken for $20. This includes 1 whole rotisserie chicken, 1 queso, 1 guac, 1 corn pico, 6 tortillas, chips and hot sauces...","og_url":"https:\/\/www.reddevelopment.com\/pvphx\/event\/backdoor-chicken-mondays-velvet-taco\/2026-08-03\/","og_site_name":"PV","og_image":[{"width":1024,"height":880,"url":"https:\/\/www.reddevelopment.com\/pvphx\/wp-content\/uploads\/sites\/32\/2026\/07\/Screenshot-2026-07-15-110507-1024x880.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.reddevelopment.com\/pvphx\/event\/backdoor-chicken-mondays-velvet-taco\/2026-08-03\/","url":"https:\/\/www.reddevelopment.com\/pvphx\/event\/backdoor-chicken-mondays-velvet-taco\/2026-08-03\/","name":"Backdoor Chicken Mondays | Velvet Taco - Things to do at PV","isPartOf":{"@id":"https:\/\/www.reddevelopment.com\/pvphx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.reddevelopment.com\/pvphx\/event\/backdoor-chicken-mondays-velvet-taco\/2026-08-03\/#primaryimage"},"image":{"@id":"https:\/\/www.reddevelopment.com\/pvphx\/event\/backdoor-chicken-mondays-velvet-taco\/2026-08-03\/#primaryimage"},"thumbnailUrl":"https:\/\/www.reddevelopment.com\/pvphx\/wp-content\/uploads\/sites\/32\/2026\/07\/Screenshot-2026-07-15-110507.png","datePublished":"2026-07-15T16:08:19+00:00","breadcrumb":{"@id":"https:\/\/www.reddevelopment.com\/pvphx\/event\/backdoor-chicken-mondays-velvet-taco\/2026-08-03\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.reddevelopment.com\/pvphx\/event\/backdoor-chicken-mondays-velvet-taco\/2026-08-03\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.reddevelopment.com\/pvphx\/event\/backdoor-chicken-mondays-velvet-taco\/2026-08-03\/#primaryimage","url":"https:\/\/www.reddevelopment.com\/pvphx\/wp-content\/uploads\/sites\/32\/2026\/07\/Screenshot-2026-07-15-110507.png","contentUrl":"https:\/\/www.reddevelopment.com\/pvphx\/wp-content\/uploads\/sites\/32\/2026\/07\/Screenshot-2026-07-15-110507.png","width":1130,"height":971},{"@type":"BreadcrumbList","@id":"https:\/\/www.reddevelopment.com\/pvphx\/event\/backdoor-chicken-mondays-velvet-taco\/2026-08-03\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.reddevelopment.com\/pvphx\/"},{"@type":"ListItem","position":2,"name":"Events","item":"https:\/\/www.reddevelopment.com\/pvphx\/events\/"},{"@type":"ListItem","position":3,"name":"Backdoor Chicken Mondays | Velvet Taco"}]},{"@type":"WebSite","@id":"https:\/\/www.reddevelopment.com\/pvphx\/#website","url":"https:\/\/www.reddevelopment.com\/pvphx\/","name":"PV","description":"A RED Development Mixed Use Landmark Property","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.reddevelopment.com\/pvphx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.reddevelopment.com\/pvphx\/wp-json\/wp\/v2\/tribe_events\/10000817","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.reddevelopment.com\/pvphx\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/www.reddevelopment.com\/pvphx\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/www.reddevelopment.com\/pvphx\/wp-json\/wp\/v2\/users\/60"}],"version-history":[{"count":0,"href":"https:\/\/www.reddevelopment.com\/pvphx\/wp-json\/wp\/v2\/tribe_events\/10000817\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.reddevelopment.com\/pvphx\/wp-json\/wp\/v2\/media\/4324"}],"wp:attachment":[{"href":"https:\/\/www.reddevelopment.com\/pvphx\/wp-json\/wp\/v2\/media?parent=10000817"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.reddevelopment.com\/pvphx\/wp-json\/wp\/v2\/tags?post=10000817"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/www.reddevelopment.com\/pvphx\/wp-json\/wp\/v2\/tribe_events_cat?post=10000817"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}